{"id":957,"date":"2020-05-10T17:40:42","date_gmt":"2020-05-10T15:40:42","guid":{"rendered":"http:\/\/carpejenn.com\/?p=957"},"modified":"2020-05-10T17:40:43","modified_gmt":"2020-05-10T15:40:43","slug":"confinement-2020","status":"publish","type":"post","link":"https:\/\/carpejenn.com\/index.php\/blog\/confinement-2020\/","title":{"rendered":"Ma vie confin\u00e9e"},"content":{"rendered":"\n<p>Hello l&#8217;amie! Cela fait maintenant un peu plus de deux mois que nous avons compl\u00e8tement chang\u00e9 nos modes de vie, #covid19 oblige. Nous vivons cette p\u00e9riode tr\u00e8s diff\u00e9remment, selon notre lieu g\u00e9ographique, notre \u00e2ge, notre activit\u00e9 professionnelle, notre situation familiale&#8230; Pour certains cette p\u00e9riode est une aubaine, pour d&#8217;autres un v\u00e9ritable enfer.<\/p>\n\n\n\n<p>En ce qui me concerne, j&#8217;ai la gr\u00e2ce de vivre cette situation plut\u00f4t positivement, je vis avec mon ch\u00e9ri, dans un appartement assez spacieux pour tous les deux. Nous sommes tous les deux en t\u00e9l\u00e9travail, et on arrive \u00e0 associer cohabitation et moment \u00e0 soi facilement.<\/p>\n\n\n\n<p>Avant de rentrer dans les d\u00e9tails de ce que le confinement m&#8217;a &#8220;apport\u00e9&#8221; je tiens \u00e0 relativiser les choses. Sur les r\u00e9seaux sociaux on voit beaucoup de &#8220;conseils&#8221; qui bien souvent ressemblent plus \u00e0 des injonctions n\u00e9gatives vivant \u00e0 nous culpabiliser, du style <strong><em>&#8220;\u00e0 la fin du confinement ta vie doit avoir chang\u00e9&#8221;<\/em><\/strong>  ou encore <em><strong>&#8220;le confinement est une aubaine pour la cr\u00e9ation&#8221;<\/strong><\/em>. Je n&#8217;ai aucun doute sur le message positif de base mais celui-ci peut \u00eatre v\u00e9cu comme stressant et anxiog\u00e8ne (de mani\u00e8re consciente ou non). Si je devais v\u00e9hiculer un message concernant le confinement ce serait &#8220;<strong><em>un jour \u00e0 la fois&#8221;<\/em><\/strong> : fais du mieux que tu peux chaque jour, peu importe le projet ou le sujet concern\u00e9.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">CE QUI A CHANGE DANS MA VIE DEPUIS LE DEBUT DU CONFINEMENT<\/h3>\n\n\n\n<p class=\"has-text-color has-vivid-green-cyan-color\">LE SPORT : MOINS D&#8217;INTENSITE, PLUS DE RESULTATS !<\/p>\n\n\n\n<p>Aussi incroyable que cela puisse para\u00eetre j&#8217;ai perdu environ 4 kilos depuis le d\u00e9but du confinement. Comme beaucoup, je suis abonn\u00e9e \u00e0 une salle de sport, comme beaucoup je me suis retrouv\u00e9e dans l&#8217;incapacit\u00e9 d&#8217;y aller. Que faire ? les r\u00e9ponses sont tellement \u00e9videntes qu&#8217;elles sont b\u00eates : j&#8217;aime courir > je vais faire des running dehors. Je n&#8217;aime pas la muscu mais je sais qu&#8217;il faut que j&#8217;en fasse : je fais de cours youtube. Qu&#8217;est ce qui a r\u00e9ussi \u00e0 faire la diff\u00e9rence du coup ? En salle, je me buttais : quand je faisais du tapis, j&#8217;en faisais une heure minimum et je me challengeais pour augmenter ma vitesse de course. Pareil concernant le renforcement : je faisais des circuits incroyablement longs et p\u00e9nibles en me disant que plus je bosse dur, plus j&#8217;aurai de r\u00e9sultats. Mon rythme \u00e9tait tr\u00e8s al\u00e9atoire, une semaine je me rendais 5 fois \u00e0 la salle, la semaine suivante 2, puis 4, puis rien pendant 2 semaines&#8230; Bref mode <em>shuffle<\/em>. Depuis le d\u00e9but du confinement, \u00e9tant moins active physiquement, je me suis dit que ce serait bien si j&#8217;arrivais \u00e0 faire 30 min d&#8217;exercice par jour pour compenser l&#8217;activit\u00e9 g\u00e9n\u00e9r\u00e9e par mes d\u00e9placements physiques en temps normal. 30 min c&#8217;est que dalle! \u00e7a passe \u00e0 une vitesse ! C&#8217;est tellement court que \u00e7a se fait facilement. Mon objectif n&#8217;\u00e9tait pas de maigrir ou de perdre du poids, car pour moi ce n&#8217;est pas 30 min par jour qui allait faire la diff\u00e9rence (et pourtant si!), mon objectif \u00e9tait de compenser le fait de ne pas bouger (t\u00e9l\u00e9travail : 8h \u00e0 10h par jour assise devant mon \u00e9cran). J&#8217;ai vraiment \u00e9t\u00e9 surprise quand j&#8217;ai commenc\u00e9 \u00e0 constater des r\u00e9sultats au bout de 3 semaines, r\u00e9sultats que je n&#8217;attendais pas. C&#8217;est \u00e0 ce moment l\u00e0 que le mot <strong>REGULARITE<\/strong> a pris tout son sens dans mon esprit. 30 min par jour 4 \u00e0 5 fois par semaine vaut mieux que 2 heures deux fois par semaine. Au bout de 4 autres semaines suppl\u00e9mentaires, les r\u00e9sultats se sont poursuivis : j&#8217;ai red\u00e9couvert mes lignes abdominales, et surprise : il s&#8217;av\u00e8re que j&#8217;ai des muscles dans les bras! Du coup je me demande si \u00e0 la fin du confinement je vais vraiment retourner \u00e0 la salle ? Ce rythme running\/cours youtube me convient assez bien, et en plus j&#8217;\u00e9conomiserai des sous.<\/p>\n\n\n\n<p class=\"has-text-color has-vivid-green-cyan-color\">LE TEMPS : UN DES BIENS LES PLUS PRECIEUX<\/p>\n\n\n\n<p>En temps normal, pour me rendre \u00e0 mon boulot, je mets environ 30 minutes porte \u00e0 porte. Soit une heure par jour, soit 5 heures par semaine ouvr\u00e9e, soit 20 heures par mois (presqu&#8217;une journ\u00e9e enti\u00e8re!) Ca a \u00e9t\u00e9 un v\u00e9ritable combat de ne pas succomber et octroyer ce temps suppl\u00e9mentaire \u00e0 ronfler plus dans le lit chaque matin et zoner sur mon ordi apr\u00e8s la journ\u00e9e de t\u00e9l\u00e9travail. Mon rythme de sommeil moyen avant le confinement \u00e9tait tr\u00e8s correct, je n&#8217;\u00e9tais pas en manque de sommeil. Je me suis fait violence chaque jour pour ne pas &#8220;gaspiller&#8221; ce temps et l&#8217;utiliser \u00e0 bon escient. J&#8217;ai 1000 activit\u00e9s que j&#8217;aimerai caser dans ma journ\u00e9e et que j&#8217;estime ne pas avoir la place pour, c&#8217;\u00e9tait donc tr\u00e8s facile d&#8217;en choisir une : <strong>le d\u00e9veloppement de comp\u00e9tences<\/strong>. Comme tu le sais peut-\u00eatre j&#8217;aime beaucoup l&#8217;art visuel, surtout la photographie. Je suis loin d&#8217;\u00eatre une professionnelle mais ce sujet m&#8217;int\u00e9resse et chaque jour je passe maintenant une heure \u00e0 m&#8217;instruire sur le sujet \u00e0 travers des contenus aussi diverses que vari\u00e9s.<\/p>\n\n\n\n<p class=\"has-text-color has-vivid-green-cyan-color\">JE MEDITE !<\/p>\n\n\n\n<p>Je ne suis pas une personne qui m\u00e9dite beaucoup, et j&#8217;ai d\u00e9cid\u00e9 d&#8217;essayer, je ne fais pas des s\u00e9ances hyper longues, entre 10 et 20 minutes max. Je mets une m\u00e9lodie apaisante en fond sonore, et je me laisse porter par le flot de mes pens\u00e9es. Au d\u00e9but c&#8217;\u00e9tait tr\u00e8s chiant, je n&#8217;avais que les sujets qui me stressaient qui me venaient \u00e0 l&#8217;esprit. N&#8217;arrivant pas \u00e0 les combattre je me suis concentr\u00e9e sur comment les solutionner si c&#8217;\u00e9tait dans mes cordes, et comment l\u00e2cher prise si je ne pouvais rien (notamment par la pri\u00e8re).<\/p>\n\n\n\n<p>Concernant les sujets de m\u00e9ditation plus gais,  j&#8217;ai plus ou moins une vision claire de mes objectifs \u00e0 long terme : fonder une famille, retourner vivre en Afrique, continuer de travailler dans un environnement qui me passionne&#8230; Et au niveau<strong> altruiste<\/strong> alors? C&#8217;est bien beau tous ces projets, mais quelle est ma valeur ajout\u00e9e en temps qu&#8217;\u00eatre humain? Je r\u00e9fl\u00e9chis de plus en plus \u00e0 impacter la vie des &#8220;autres&#8221; d&#8217;une mani\u00e8re positive. Je sais que cela ne passe pas forc\u00e9ment par un projet m\u00e9ga balaise, la bienveillance c&#8217;est tous les jours, dans les petits actes et \u00e7a commence avec son entourage proche, et je trouve qu&#8217;aujourd&#8217;hui je n&#8217;en fais pas assez. <\/p>\n\n\n\n<p class=\"has-text-color has-vivid-green-cyan-color\">LES ECONOMIES : 200\u20ac EN MOYENNE PAR MOIS !<\/p>\n\n\n\n<p>Mon compte bancaire vit sa best life depuis mars : Entre le navigo rembours\u00e9, l&#8217;essence que je n&#8217;ai pas \u00e0 mettre dans ma voiture vu que je ne roule pas, les courses en gros, la salle de sport qui ne me pr\u00e9l\u00e8ve pas, j&#8217;\u00e9conomise environ 200\u20ac par mois, pas mal non? Evidemment premier r\u00e9flexe, tout claquer dans les derni\u00e8res air force&#8230;. Mais non non non, aint about that life anymore ! on reste concentr\u00e9, on investit dans les projets !<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Si le confinement m&#8217;a aid\u00e9 dans les domaines cit\u00e9s ci-dessus, il m&#8217;a aussi apport\u00e9 un lot de d\u00e9ception : <\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Le d\u00e9calage de mon mariage.<\/strong> Nous avons fait la dot en 2018 et pr\u00e9vu de faire le reste (marie, \u00e9glise) cet \u00e9t\u00e9, il a fallu tout mettre en pause, je te raconte m\u00eame pas la merde logistique qui en suit&#8230;<\/li><li><strong>Le d\u00e9calage du mariage d&#8217;une de mes meilleures amies<\/strong>, pr\u00e9vu ce printemps, et par cons\u00e9quent l&#8217;annulation de mon voyage au Canada pour m&#8217;y rendre. Pas de remboursement du billet par la compagnie a\u00e9rienne, mais un avoir valable un an (c&#8217;est d\u00e9j\u00e0 \u00e7a)<\/li><li><strong>Etre loin des siens<\/strong> : je pense que c&#8217;est la douleur la plus lourdement partag\u00e9e. Ne pas voir sa famille, ses amis. Etre impuissant face \u00e0 la d\u00e9tresse de certains de nos proches, ne pas pouvoir dire au revoir \u00e0 ce qui partent&#8230; Plusieurs personnes parmi mes proches ont \u00e9t\u00e9 contamin\u00e9s, et malheureusement certains ont succomb\u00e9 au virus.<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">LE MOT DE LA FIN<\/h4>\n\n\n\n<p>M\u00eame si on peut trouver des points positifs dans cette situation, elle reste quand m\u00eame tragique au niveau mondial. Elle remet en cause de mani\u00e8re tr\u00e8s flagrante <strong>notre style de vie et l&#8217;impact n\u00e9gatif de la mondialisation<\/strong>&nbsp;(notamment&nbsp;\u00e0&nbsp;travers&nbsp;notre&nbsp;d\u00e9pendance&nbsp;\u00e0&nbsp;la&nbsp;Chine&nbsp;qui&nbsp;aujourd&#8217;hui&nbsp;est&nbsp;clairement&nbsp;l&#8217;usine&nbsp;du&nbsp;monde). On peut avoir l&#8217;impression qu&#8217;en tant qu&#8217;individu, notre poids est tr\u00e8s relatif pour un changement vers un monde meilleur, et cela est vrai. Mais le plus important \u00e0 mon sens c&#8217;est de contribuer, <strong>de faire sa part.<\/strong><\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Et toi, quels changements as-tu v\u00e9cus pendant ce confinement ? Dis moi tout en commentaire &nbsp;&#x1f447;<\/h5>\n","protected":false},"excerpt":{"rendered":"<p>Hello l&#8217;amie! Cela fait maintenant un peu plus de deux mois que nous avons compl\u00e8tement chang\u00e9 nos modes de vie, #covid19 oblige. Nous vivons cette p\u00e9riode tr\u00e8s diff\u00e9remment, selon notre lieu g\u00e9ographique, notre \u00e2ge, notre activit\u00e9 professionnelle, notre situation familiale&#8230; Pour certains cette p\u00e9riode est une aubaine, pour d&#8217;autres un v\u00e9ritable enfer. En ce qui [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1005,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[26,41,40,17],"class_list":["post-957","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-carpejenn","tag-confinement","tag-covid19","tag-lifestyle"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/carpejenn.com\/index.php\/wp-json\/wp\/v2\/posts\/957"}],"collection":[{"href":"https:\/\/carpejenn.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/carpejenn.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/carpejenn.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/carpejenn.com\/index.php\/wp-json\/wp\/v2\/comments?post=957"}],"version-history":[{"count":4,"href":"https:\/\/carpejenn.com\/index.php\/wp-json\/wp\/v2\/posts\/957\/revisions"}],"predecessor-version":[{"id":1006,"href":"https:\/\/carpejenn.com\/index.php\/wp-json\/wp\/v2\/posts\/957\/revisions\/1006"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/carpejenn.com\/index.php\/wp-json\/wp\/v2\/media\/1005"}],"wp:attachment":[{"href":"https:\/\/carpejenn.com\/index.php\/wp-json\/wp\/v2\/media?parent=957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/carpejenn.com\/index.php\/wp-json\/wp\/v2\/categories?post=957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/carpejenn.com\/index.php\/wp-json\/wp\/v2\/tags?post=957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}